{"id":270,"count":21,"description":"","link":"https:\/\/rfid-pro.com\/de\/rfid-applications\/animal-identification\/","name":"Tieridentifikation","slug":"animal-identification","taxonomy":"category","parent":266,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/rfid-pro.com\/de\/wp-json\/wp\/v2\/categories\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rfid-pro.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/rfid-pro.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/rfid-pro.com\/de\/wp-json\/wp\/v2\/categories\/266"}],"wp:post_type":[{"href":"https:\/\/rfid-pro.com\/de\/wp-json\/wp\/v2\/posts?categories=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}